{"id":5429,"date":"2020-04-06T14:27:01","date_gmt":"2020-04-06T14:27:01","guid":{"rendered":"http:\/\/www.psicosedna.com\/cat\/?p=5429"},"modified":"2020-04-20T16:50:26","modified_gmt":"2020-04-20T16:50:26","slug":"dol-en-solitud","status":"publish","type":"post","link":"http:\/\/www.psicosedna.com\/cat\/blog\/2020\/04\/06\/dol-en-solitud\/","title":{"rendered":"Dol en solitud"},"content":{"rendered":"<p><strong>Dol en solitud<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Som \u00e9ssers socials, i ho som per a tot. Tamb\u00e9 per a gestionar el nostre dolor. Aquesta situaci\u00f3 tan excepcional on estem obligats a romandre a casa, on estem separats de la nostra fam\u00edlia, on \u00e9s m\u00e9s dif\u00edcil escapar dels nostres pensaments.<\/p>\n<p>&nbsp;<\/p>\n<p>Qu\u00e8 fem amb el nostre dolor davant la mort d\u2019un \u00e9sser estimat? Una mort que no ens ha perm\u00e8s acompanyar-li, que no ens ha perm\u00e8s comunicar-nos gaireb\u00e9 amb ell\/ella, una mort m\u00e9s dura i sense poder compartir el nostre dolor amb els nostres afins, no sols de paraula si no amb petons, abra\u00e7ades&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>Doncs \u00e9s dif\u00edcil, per\u00f2 hem de gestionar en la mesura del possible el nostre dolor. Hem d\u2019expressar-ho, hem de sentir-ho i ordenar-ho. Per qu\u00e8? Doncs perqu\u00e8 d\u2019una altra manera aquest dolor ens bloquejar\u00e0, no ens deixar\u00e0 trobar l\u2019equilibri necessari per a sostenir aquesta situaci\u00f3 de tancament i no permetr\u00e0 un entorn saludable per a cap membre de la conviv\u00e8ncia.<\/p>\n<p><a href=\"http:\/\/www.psicosedna.com\/cat\/wp-content\/uploads\/2020\/04\/candle-4587034_1920.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-5430 size-medium\" src=\"http:\/\/www.psicosedna.com\/cat\/wp-content\/uploads\/2020\/04\/candle-4587034_1920-300x200.jpg\" alt=\"candle-4587034_1920\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.psicosedna.com\/cat\/wp-content\/uploads\/2020\/04\/candle-4587034_1920-300x200.jpg 300w, http:\/\/www.psicosedna.com\/cat\/wp-content\/uploads\/2020\/04\/candle-4587034_1920-1024x682.jpg 1024w, http:\/\/www.psicosedna.com\/cat\/wp-content\/uploads\/2020\/04\/candle-4587034_1920.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00c9s complicat exposar passos per a gestionar aquest dolor, per\u00f2 intentar\u00e9 fer alguna cosa semblant a un protocol perqu\u00e8 \u00e9s important ser flexibles amb nosaltres mateixos i no for\u00e7ar les situacions. No som m\u00e0quines, som persones amb m\u00faltiples habilitats i punts febles que hem de tenir en compte.<\/p>\n<p>Segurament la not\u00edcia de la mort d\u2019un \u00e9sser estimat, ens arribar\u00e0 despr\u00e9s d\u2019uns dies o setmanes de trobar-se en quarantena en un hospital. Sense gaireb\u00e9 comunicaci\u00f3, i per la impossibilitat de parlar-los o acompanyar-los.<\/p>\n<p>&nbsp;<\/p>\n<p>Per tant veiem que no \u00e9s un dol normalitzat, que no sols suposa el dolor per la p\u00e8rdua de l\u2019\u00e9sser estimat. Tamb\u00e9 hi haur\u00e0 impot\u00e8ncia per no poder actuar, hi haur\u00e0 ansietat per l\u2019espera de not\u00edcies, i el no saber que fer ni com, hi haur\u00e0 r\u00e0bia per no entendre b\u00e9 la situaci\u00f3 i una dif\u00edcil acceptaci\u00f3 de la mort.<\/p>\n<p>&nbsp;<\/p>\n<p>B\u00e9, totes aquestes emocions pertanyen al dolor, la r\u00e0bia, la impot\u00e8ncia, l\u2019ansietat&#8230; aix\u00ed que necessitem expressar-les, necessitem recon\u00e8ixer-les i cedir-los el seu espai, necessitem que es reequilibrin i donin pas a una acceptaci\u00f3 activa i a una resoluci\u00f3 de la tristesa de forma m\u00e9s calmada.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019empipament \u00e9s el preludi del dolor, \u00e9s una manera que tenim els humans d\u2019enfrontar-nos activament a no patir aquest dolor. Si m\u2019enfado, si busco culpables, si dirigeixo la meva ira cap a l\u2019entorn i la situaci\u00f3 aconsegueixo al principi evitar o no passar per aquest dolor intens que suposa perdre alg\u00fa. Aquest dolor intens que no volem sentir, per\u00f2 que nom\u00e9s sentint-ho s\u2019anir\u00e0 o es gestionar\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>La persona que marxa, marxa amb tot el que li hem donat, li hem dit, li hem fet sentir. Sap que sent pel seu entorn i el comiat no el canviar\u00e0. Per a la persona que es queda li falta all\u00f2 m\u00e9s, sempre una mica m\u00e9s, els comiats s\u00f3n durs i m\u00e9s si sabem que \u00e9s l\u2019\u00faltima. Per aix\u00f2 ser\u00e0 un dol m\u00e9s dur. Per\u00f2 si aconsegueixes sortir de la r\u00e0bia r\u00e0pid i et dediques a cuidar-te en el teu dolor ser\u00e0 m\u00e9s f\u00e0cil gestionar-lo.<\/p>\n<p>&nbsp;<\/p>\n<p>Molt d\u2019\u00e0nim a tots\/es en aquesta situaci\u00f3 tan dif\u00edcil. No dubteu en contactar amb nosaltres si voleu aprofundir m\u00e9s o tenir m\u00e9s informaci\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Beatriz Rodr\u00edguez Batlle, Psic\u00f2loga col\u00b7legiada n\u00ba20093<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dol en solitud &nbsp; Som \u00e9ssers socials, i ho som per a tot. Tamb\u00e9 per a gestionar el nostre dolor. Aquesta situaci\u00f3 tan excepcional on estem obligats a romandre a casa, on estem separats de la nostra fam\u00edlia, on \u00e9s m\u00e9s dif\u00edcil escapar dels nostres pensaments. &nbsp; Qu\u00e8 fem amb el nostre dolor davant la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,21,24],"tags":[],"_links":{"self":[{"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/posts\/5429"}],"collection":[{"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/comments?post=5429"}],"version-history":[{"count":2,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/posts\/5429\/revisions"}],"predecessor-version":[{"id":5432,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/posts\/5429\/revisions\/5432"}],"wp:attachment":[{"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/media?parent=5429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/categories?post=5429"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.psicosedna.com\/cat\/wp-json\/wp\/v2\/tags?post=5429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}